{"id":109141,"date":"2025-08-01T20:29:07","date_gmt":"2025-08-01T18:29:07","guid":{"rendered":"https:\/\/onesportmallorca.com\/?post_type=product&#038;p=109141"},"modified":"2025-08-01T20:38:52","modified_gmt":"2025-08-01T18:38:52","slug":"zapatillas-kswiss-express-light-3-hb-wht-nmnt-npstpnk-98563106","status":"publish","type":"product","link":"https:\/\/onesportmallorca.com\/en\/producto\/zapatillas-kswiss-express-light-3-hb-wht-nmnt-npstpnk-98563106\/","title":{"rendered":"Zapatillas Kswiss Express Light 3 HB WHT\/NMNT\/NPSTPNK (98563106)"},"content":{"rendered":"<p>La Express Light 3 HB Padel es una zapatilla de p\u00e1del ligera dise\u00f1ada para el rendimiento en la pista y un gran nivel de comodidad. La parte superior cuenta con DuraWrap Flex, una estructura de RPU moldeada de nuevo dise\u00f1o que proporciona un soporte flexible y protecci\u00f3n contra la fricci\u00f3n. En el interior, un collar\u00edn de tobillo bien acolchado proporciona comodidad y estabilidad, mientras que una plantilla de espuma troquelada agrega amortiguaci\u00f3n reactiva bajo los pies. La Express Light 3 tiene una suela HB con patrones de espiga con ranuras profundas para una tracci\u00f3n excepcional en superficies de canchas de p\u00e1del en interiores y exteriores.<\/p>\n<ul>\n<li>Parte superior de cuero sint\u00e9tico<\/li>\n<li>Forro de cuello de tela<\/li>\n<li>Suela de caucho moldeado<\/li>\n<li>Entresuela de CMEVA<\/li>\n<li>Plantilla de EVA moldeada<\/li>\n<li>Cierre de cordones<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La Express Light 3 HB Padel es una zapatilla de p\u00e1del ligera dise\u00f1ada para el rendimiento en la pista y<\/p>\n","protected":false},"featured_media":109180,"template":"","meta":[],"product_brand":[],"product_cat":[2240,6940,6941],"product_tag":[],"class_list":["post-109141","product","type-product","status-publish","has-post-thumbnail","product_cat-footwear","product_cat-k-swiss-en","product_cat-padel-en-2","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","rtwpvg-product"],"supplier_id":null,"supplier_sku":"","barcode":null,"atum_controlled":true,"out_stock_date":null,"out_stock_threshold":null,"inheritable":true,"inbound_stock":0,"stock_on_hold":0,"sold_today":3,"sales_last_days":4,"reserved_stock":0,"customer_returns":0,"warehouse_damage":0,"lost_in_post":0,"other_logs":0,"out_stock_days":null,"lost_sales":0,"has_location":true,"update_date":"2026-02-22T11:57:19","atum_locations":[{"id":5967,"name":"Shop Duva","slug":"shop_duva"},{"id":6282,"name":"Tienda Onesport","slug":"tienda_onesport"}],"atum_stock_status":"outofstock","restock_status":false,"low_stock_amount":"","sales_update_date":"2025-09-09T11:41:17","calc_backorders":null,"_links":{"self":[{"href":"https:\/\/onesportmallorca.com\/en\/wp-json\/wp\/v2\/product\/109141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onesportmallorca.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/onesportmallorca.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onesportmallorca.com\/en\/wp-json\/wp\/v2\/media\/109180"}],"wp:attachment":[{"href":"https:\/\/onesportmallorca.com\/en\/wp-json\/wp\/v2\/media?parent=109141"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/onesportmallorca.com\/en\/wp-json\/wp\/v2\/product_brand?post=109141"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/onesportmallorca.com\/en\/wp-json\/wp\/v2\/product_cat?post=109141"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/onesportmallorca.com\/en\/wp-json\/wp\/v2\/product_tag?post=109141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}