{"id":140253,"date":"2026-02-04T14:34:34","date_gmt":"2026-02-04T13:34:34","guid":{"rendered":"https:\/\/onesportmallorca.com\/?post_type=product&#038;p=140253"},"modified":"2026-02-06T12:22:35","modified_gmt":"2026-02-06T11:22:35","slug":"zapatillas-bullpadel-indiga-w-26v-rosa","status":"publish","type":"product","link":"https:\/\/onesportmallorca.com\/ca\/producto\/zapatillas-bullpadel-indiga-w-26v-rosa\/","title":{"rendered":"Zapatillas Bullpadel INDIGA W 26V Rosa"},"content":{"rendered":"<p>Este modelo de zapatilla es ideal para jugadoras de nivel iniciaci\u00f3n o intermedio que buscan un calzado flexible, c\u00f3modo y con m\u00e1ximo agarre. Su suela de espiga pura garantiza una tracci\u00f3n excelente en cada movimiento, mientras que el tejido mesh altamente transpirable mantiene el pie fresco y ventilado durante todo el juego.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este modelo de zapatilla es ideal para jugadoras de nivel iniciaci\u00f3n o intermedio que buscan un calzado flexible, c\u00f3modo y<\/p>\n","protected":false},"featured_media":140397,"template":"","meta":[],"product_brand":[7211],"product_cat":[6415,2239],"product_tag":[],"class_list":["post-140253","product","type-product","status-publish","has-post-thumbnail","product_brand-bullpadel","product_cat-bullpadel-ca","product_cat-calcat","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","rtwpvg-product"],"supplier_id":null,"supplier_sku":"","barcode":null,"atum_controlled":true,"out_stock_date":null,"out_stock_threshold":null,"inheritable":true,"inbound_stock":null,"stock_on_hold":0,"sold_today":5,"sales_last_days":5,"reserved_stock":null,"customer_returns":null,"warehouse_damage":null,"lost_in_post":null,"other_logs":null,"out_stock_days":null,"lost_sales":0,"has_location":true,"update_date":"2026-06-19T07:30:04","atum_locations":[{"id":5967,"name":"Shop Duva","slug":"shop_duva"}],"atum_stock_status":"outofstock","restock_status":false,"low_stock_amount":"","sales_update_date":"2025-03-27T11:02:44","calc_backorders":null,"_links":{"self":[{"href":"https:\/\/onesportmallorca.com\/ca\/wp-json\/wp\/v2\/product\/140253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onesportmallorca.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/onesportmallorca.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onesportmallorca.com\/ca\/wp-json\/wp\/v2\/media\/140397"}],"wp:attachment":[{"href":"https:\/\/onesportmallorca.com\/ca\/wp-json\/wp\/v2\/media?parent=140253"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/onesportmallorca.com\/ca\/wp-json\/wp\/v2\/product_brand?post=140253"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/onesportmallorca.com\/ca\/wp-json\/wp\/v2\/product_cat?post=140253"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/onesportmallorca.com\/ca\/wp-json\/wp\/v2\/product_tag?post=140253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}